{"id":8914,"date":"2024-04-29T15:54:10","date_gmt":"2024-04-29T18:54:10","guid":{"rendered":"https:\/\/suburbionoar.com.br\/?p=8914"},"modified":"2024-04-29T15:54:12","modified_gmt":"2024-04-29T18:54:12","slug":"casal-e-flagrado-furtando-celulares-e-relogio-no-aeroporto-de-salvador","status":"publish","type":"post","link":"https:\/\/suburbionoar.com.br\/index.php\/2024\/04\/29\/casal-e-flagrado-furtando-celulares-e-relogio-no-aeroporto-de-salvador\/","title":{"rendered":"Casal \u00e9 flagrado furtando celulares e rel\u00f3gio no Aeroporto de Salvador"},"content":{"rendered":"\n<p>Um casal, que teria vindo a Salvador para participar de um encontro do Partido Socialismo e Liberdade (PSOL), foi flagrado por c\u00e2meras de seguran\u00e7a do Aeroporto Internacional de Salvador, furtando dois aparelhos celulares e um rel\u00f3gio que foram esquecidos na esteira por outro casal que havia acabado de passar pelo raio-x, neste domingo (28).<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o homem e a mulher que aparecem no v\u00eddeo, agiram juntos. Enquanto ele escondeu os aparelhos celulares, ela guardou o rel\u00f3gio na mochila. O casal que esqueceu os objetos na esteira solicitou a ajuda de funcion\u00e1rios do aeroporto assim que percebeu que haviam sido furtados. Logo, os criminosos foram identificados e a Pol\u00edcia Federal foi informada da situa\u00e7\u00e3o, conseguindo prender o casal em flagrante, ainda antes do embarque.&nbsp;<\/p>\n\n\n\n<p>Eles foram indiciados por furto qualificado e v\u00e3o passar por audi\u00eancia de cust\u00f3dia. Uma terceira mulher que estava com o casal n\u00e3o foi presa, pois a sua participa\u00e7\u00e3o n\u00e3o foi constatada na an\u00e1lise das imagens. Ainda segundo informa\u00e7\u00f5es, os tr\u00eas indiv\u00edduos estavam em Salvador desde a \u00faltima quinta, participando de um evento do PSOL.\u00a0 <\/p>\n\n\n\n<p>Fonte: Bahia Not\u00edcias <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um casal, que teria vindo a Salvador para participar de um encontro do Partido Socialismo e Liberdade (PSOL), foi flagrado por c\u00e2meras de seguran\u00e7a do Aeroporto Internacional de Salvador, furtando dois aparelhos celulares e um rel\u00f3gio que foram esquecidos na esteira por outro casal que havia acabado de passar pelo raio-x, neste domingo (28). Segundo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-8914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8914"}],"version-history":[{"count":1,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8914\/revisions"}],"predecessor-version":[{"id":8916,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8914\/revisions\/8916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/8915"}],"wp:attachment":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}