{"id":8910,"date":"2024-04-29T15:45:54","date_gmt":"2024-04-29T18:45:54","guid":{"rendered":"https:\/\/suburbionoar.com.br\/?p=8910"},"modified":"2024-04-29T15:45:56","modified_gmt":"2024-04-29T18:45:56","slug":"professores-reforcam-paralisacao-de-categoria-em-feira-ato-representa-27-cidades-de-regiao","status":"publish","type":"post","link":"https:\/\/suburbionoar.com.br\/index.php\/2024\/04\/29\/professores-reforcam-paralisacao-de-categoria-em-feira-ato-representa-27-cidades-de-regiao\/","title":{"rendered":"Professores refor\u00e7am paralisa\u00e7\u00e3o de categoria em Feira; ato representa 27 cidades de regi\u00e3o"},"content":{"rendered":"\n<p>Uma manifesta\u00e7\u00e3o de professores da rede estadual foi realizada nesta segunda-feira (29) em\u00a0Feira de Santana. O protesto faz parte da paralisa\u00e7\u00e3o de 48 horas deflagrada pelo sindicato da categoria [APLB].<\/p>\n\n\n\n<p>O ato que representou os docentes de Feira de Santana e mais 26 cidades cobra reajuste salarial de 10%, al\u00e9m de pagamento da terceira parcela de precat\u00f3rios n\u00e3o quitados e reestrutura\u00e7\u00e3o do plano de carreiras. <\/p>\n\n\n\n<p>A contraproposta do governo, de 5,69% de reajuste, n\u00e3o foi aceita\u00a0em assembleia da categoria, realizada na \u00faltima quinta-feira (25). Segundo o\u00a0Acorda Cidade, a manifesta\u00e7\u00e3o em Feira de Santana ocorreu em frente ao N\u00facleo Territorial de Educa\u00e7\u00e3o (NTE-19).<\/p>\n\n\n\n<p>Fonte: Bahia Not\u00edcias \u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma manifesta\u00e7\u00e3o de professores da rede estadual foi realizada nesta segunda-feira (29) em\u00a0Feira de Santana. O protesto faz parte da paralisa\u00e7\u00e3o de 48 horas deflagrada pelo sindicato da categoria [APLB]. O ato que representou os docentes de Feira de Santana e mais 26 cidades cobra reajuste salarial de 10%, al\u00e9m de pagamento da terceira parcela [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-8910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8910"}],"version-history":[{"count":1,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8910\/revisions"}],"predecessor-version":[{"id":8912,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8910\/revisions\/8912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/8911"}],"wp:attachment":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}