{"id":5060,"date":"2023-10-19T10:35:14","date_gmt":"2023-10-19T13:35:14","guid":{"rendered":"https:\/\/suburbionoar.com.br\/?p=5060"},"modified":"2023-10-19T10:35:16","modified_gmt":"2023-10-19T13:35:16","slug":"bruno-reis-cai-na-danca-ao-entregar-casas-do-programa-morar-melhor","status":"publish","type":"post","link":"https:\/\/suburbionoar.com.br\/index.php\/2023\/10\/19\/bruno-reis-cai-na-danca-ao-entregar-casas-do-programa-morar-melhor\/","title":{"rendered":"Bruno Reis cai na dan\u00e7a ao entregar casas do programa &#8220;Morar Melhor&#8221;"},"content":{"rendered":"\n<p>Durante a entrega de 100 casas do programa &#8220;Morar Melhor&#8221;, na manh\u00e3 desta ter\u00e7a-feira (17), no bairro de Boa Vista de S\u00e3o Caetano, em Salvador, o prefeito Bruno Reis (UB) caiu na dan\u00e7a e se denominou &#8220;arrocheiro.&#8221;<\/p>\n\n\n\n<p>O v\u00eddeo, publicado nas redes sociais de Bruno, caiu na gra\u00e7a do povo e est\u00e1 repercutindo entre os seguidores.&nbsp;&#8220;Gostei dos passos viu Bruno&#8221;, disse um seguidor.&nbsp;Outro&nbsp;disparou &#8220;O maior Programa , O Programa Morar Melhor.. E eu estava l\u00e1 e que cantoria,&nbsp;show&#8221;.<\/p>\n\n\n\n<p>Fonte: Varela Net <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a entrega de 100 casas do programa &#8220;Morar Melhor&#8221;, na manh\u00e3 desta ter\u00e7a-feira (17), no bairro de Boa Vista de S\u00e3o Caetano, em Salvador, o prefeito Bruno Reis (UB) caiu na dan\u00e7a e se denominou &#8220;arrocheiro.&#8221; O v\u00eddeo, publicado nas redes sociais de Bruno, caiu na gra\u00e7a do povo e est\u00e1 repercutindo entre os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"class_list":["post-5060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5060"}],"version-history":[{"count":1,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5060\/revisions"}],"predecessor-version":[{"id":5062,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5060\/revisions\/5062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/5061"}],"wp:attachment":[{"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suburbionoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}